{"id":375,"date":"2021-11-27T06:50:59","date_gmt":"2021-11-27T06:50:59","guid":{"rendered":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/?page_id=375"},"modified":"2021-11-27T06:52:10","modified_gmt":"2021-11-27T06:52:10","slug":"la-formazione","status":"publish","type":"page","link":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/indice\/la-formazione\/","title":{"rendered":"LA FORMAZIONE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"375\" class=\"elementor elementor-375\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e83b528 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e83b528\" data-element_type=\"section\" id=\"mybread\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1902ae\" data-id=\"e1902ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-255ff7e elementor-widget elementor-widget-shortcode\" data-id=\"255ff7e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t\t<!-- Flexy Breadcrumb -->\r\n\t\t\t<div class=\"fbc fbc-page\">\r\n\r\n\t\t\t\t<!-- Breadcrumb wrapper -->\r\n\t\t\t\t<div class=\"fbc-wrap\">\r\n\r\n\t\t\t\t\t<!-- Ordered list-->\r\n\t\t\t\t\t<ol class=\"fbc-items\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\r\n\t\t\t\t\t\t            <li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\">\r\n                <span itemprop=\"name\">\r\n                    <!-- Home Link -->\r\n                    <a itemprop=\"item\" href=\"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\">\r\n                    \r\n                                                    <i class=\"fa fa-home\" aria-hidden=\"true\"><\/i>PTOF 2025 - 2028                    <\/a>\r\n                <\/span>\r\n                <meta itemprop=\"position\" content=\"1\" \/><!-- Meta Position-->\r\n             <\/li><li><span class=\"fbc-separator\">\/<\/span><\/li><li class=\"active\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\" title=\"LA FORMAZIONE\">LA FORMAZIONE<\/span><meta itemprop=\"position\" content=\"2\" \/><\/li>\t\t\t\t\t<\/ol>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-443f2b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"443f2b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09688c0\" data-id=\"09688c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef4ed2f elementor-widget elementor-widget-spacer\" data-id=\"ef4ed2f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50669c4 elementor-widget elementor-widget-heading\" data-id=\"50669c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LA FORMAZIONE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-524ba2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"524ba2f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb5d907\" data-id=\"bb5d907\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8062660 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8062660\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4631e3 contenutolungo elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4631e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a03cb9\" data-id=\"3a03cb9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3639b0a elementor-widget elementor-widget-text-editor\" data-id=\"3639b0a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le aree&nbsp; che dovranno essere incluse nel <\/span><b>piano di formazione dei docenti<\/b><span style=\"font-weight: 400;\"> devono essere frutto dell\u2019intreccio tra<\/span><\/p>\n<p><span style=\"font-weight: 400;\">a) le priorit\u00e0 definite dal piano triennale della formazione del Ministero Istruzione;<br><\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem;\">b) evidenze del RAV e delle Prove INVALSI<br><\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem;\">c) dimensioni chiave del PTOF<br><\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem;\">d) dimensioni dell\u2019innovazione didattica definite dalla partecipazione a rete anche internazionali.<br><\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem;\">e) area digitale in ordine alla DDI.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Per quanto riguarda questo punto, L\u2019Animatore digitale e i docenti del Team di innovazione digitale garantiscono il necessario sostegno alla DDI, progettando e realizzando <\/span><b>attivit\u00e0 di formazione interna e supporto rivolte al personale scolastico docente<\/b><span style=\"font-weight: 400;\"> e non docente, attraverso<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">corsi di formazione, previa analisi del fabbisogno formativo attraverso sondaggio on line<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">affiancamento tramite un Help desk<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">la creazione e\/o la condivisione di guide e tutorial in formato digitale&nbsp;&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">attivit\u00e0 di alfabetizzazione digitale rivolte alle studentesse e agli studenti dell\u2019Istituto, anche in modalit\u00e0 peer tutoring<\/span><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LA FORMAZIONE Le aree&nbsp; che dovranno essere incluse nel piano di formazione dei docenti devono essere frutto dell\u2019intreccio tra a) le priorit\u00e0 definite dal piano triennale della formazione del Ministero Istruzione;b) evidenze del RAV e delle Prove INVALSIc) dimensioni chiave del PTOFd) dimensioni dell\u2019innovazione didattica definite dalla partecipazione a rete anche internazionali.e) area digitale in &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/indice\/la-formazione\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;LA FORMAZIONE&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":19,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-375","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/pages\/375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/comments?post=375"}],"version-history":[{"count":5,"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/pages\/375\/revisions"}],"predecessor-version":[{"id":456,"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/pages\/375\/revisions\/456"}],"up":[{"embeddable":true,"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/pages\/19"}],"wp:attachment":[{"href":"https:\/\/ptof.liceoattiliobertolucci.org\/25-28\/wp-json\/wp\/v2\/media?parent=375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}